{"id":425,"count":3,"description":"","link":"https:\/\/tiltcylinder.com\/tr\/tag\/nut-hydraulic\/","name":"nut hydraulic","slug":"nut-hydraulic","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/tr\/wp-json\/wp\/v2\/tags\/425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/tr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/tr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/tr\/wp-json\/wp\/v2\/posts?tags=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}