{"id":962,"count":1,"description":"","link":"https:\/\/tiltcylinder.com\/ru\/tag\/tank-cylinder\/","name":"tank cylinder","slug":"tank-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/tags\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/posts?tags=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}