{"id":481,"count":4,"description":"","link":"https:\/\/tiltcylinder.com\/ru\/tag\/outrigger-hydraulic-cylinder\/","name":"outrigger hydraulic cylinder","slug":"outrigger-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/tags\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/ru\/wp-json\/wp\/v2\/posts?tags=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}