{"id":349,"count":4,"description":"","link":"https:\/\/tiltcylinder.com\/pl\/tag\/dump-truck-lift-hydraulic-cylinder\/","name":"dump truck lift hydraulic cylinder","slug":"dump-truck-lift-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/tags\/349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/posts?tags=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}