{"id":1070,"count":1,"description":"","link":"https:\/\/tiltcylinder.com\/pl\/tag\/hydraulic-lifter\/","name":"hydraulic lifter","slug":"hydraulic-lifter","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/tags\/1070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/pl\/wp-json\/wp\/v2\/posts?tags=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}