{"id":857,"count":1,"description":"","link":"https:\/\/tiltcylinder.com\/nn\/tag\/5-stage-hydraulic-cylinder\/","name":"5 stage hydraulic cylinder","slug":"5-stage-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/nn\/wp-json\/wp\/v2\/tags\/857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/nn\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/nn\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/nn\/wp-json\/wp\/v2\/posts?tags=857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}