{"id":855,"count":1,"description":"","link":"https:\/\/tiltcylinder.com\/ko\/tag\/truck-lift-gate-hydraulic\/","name":"truck lift gate hydraulic","slug":"truck-lift-gate-hydraulic","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/ko\/wp-json\/wp\/v2\/tags\/855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/ko\/wp-json\/wp\/v2\/posts?tags=855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}