{"id":888,"count":8,"description":"","link":"https:\/\/tiltcylinder.com\/id\/tag\/pump-hydraulic-case\/","name":"pump hydraulic case","slug":"pump-hydraulic-case","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/id\/wp-json\/wp\/v2\/tags\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/id\/wp-json\/wp\/v2\/posts?tags=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}