{"id":934,"count":1,"description":"","link":"https:\/\/tiltcylinder.com\/hi\/tag\/hydraulic-scissor-lift\/","name":"hydraulic scissor lift","slug":"hydraulic-scissor-lift","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/hi\/wp-json\/wp\/v2\/tags\/934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/hi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/hi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/hi\/wp-json\/wp\/v2\/posts?tags=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}