{"id":414,"count":5,"description":"","link":"https:\/\/tiltcylinder.com\/es\/tag\/10-ton-hydraulic-cylinder\/","name":"10 ton hydraulic cylinder","slug":"10-ton-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/tags\/414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/posts?tags=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}