{"id":258,"count":1,"description":"","link":"https:\/\/tiltcylinder.com\/es\/tag\/hydraulic-boat\/","name":"hydraulic boat","slug":"hydraulic-boat","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/tags\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/es\/wp-json\/wp\/v2\/posts?tags=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}