{"id":525,"count":3,"description":"","link":"https:\/\/tiltcylinder.com\/de\/tag\/hydraulic-bar\/","name":"hydraulic bar","slug":"hydraulic-bar","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tiltcylinder.com\/de\/wp-json\/wp\/v2\/tags\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiltcylinder.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tiltcylinder.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tiltcylinder.com\/de\/wp-json\/wp\/v2\/posts?tags=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}